{"id":8734,"date":"2025-08-05T16:10:32","date_gmt":"2025-08-05T08:10:32","guid":{"rendered":"https:\/\/toquartz.com\/?p=8734"},"modified":"2025-09-30T17:11:54","modified_gmt":"2025-09-30T09:11:54","slug":"custom-uv-grade-dual-path-quartz-cuvette","status":"publish","type":"post","link":"https:\/\/toquartz.com\/de\/custom-uv-grade-dual-path-quartz-cuvette\/","title":{"rendered":"Spectral-Flat Custom UV-Grade Dual-Path Quarzk\u00fcvette f\u00fcr UV-Vis Anwendungen -TOQUARTZ\u00ae"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"8734\" class=\"elementor elementor-8734\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9008243 e-flex e-con-boxed e-con e-parent\" data-id=\"9008243\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-95ace4e e-con-full e-flex e-con e-child\" data-id=\"95ace4e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c24aace elementor-widget elementor-widget-shortcode\" data-id=\"c24aace\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t\t<!-- Flexy Breadcrumb -->\r\n\t\t\t<div class=\"fbc fbc-page\">\r\n\r\n\t\t\t\t<!-- Breadcrumb wrapper -->\r\n\t\t\t\t<div class=\"fbc-wrap\">\r\n\r\n\t\t\t\t\t<!-- Ordered list-->\r\n\t\t\t\t\t<ol class=\"fbc-items\" itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\">\r\n\t\t\t\t\t\t            <li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\">\r\n                <span itemprop=\"name\">\r\n                    <!-- Home Link -->\r\n                    <a itemprop=\"item\" href=\"https:\/\/toquartz.com\/de\/\">\r\n                    \r\n                                                    <i class=\"fa fa-home\" aria-hidden=\"true\"><\/i>Startseite                    <\/a>\r\n                <\/span>\r\n                <meta itemprop=\"position\" content=\"1\" \/><!-- Meta Position-->\r\n             <\/li><li><span class=\"fbc-separator\">\/<\/span><\/li><li class=\"active\" itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\" title=\"Spectral-Flat Custom UV-Grade Dual-Path Quarzk\u00fcvette f\u00fcr UV-Vis Anwendungen -TOQUARTZ\u00ae\">Spectral-Flat Custom UV-Grade Dual-Path...<\/span><meta itemprop=\"position\" content=\"2\" \/><\/li>\t\t\t\t\t<\/ol>\r\n\t\t\t\t\t<div class=\"clearfix\"><\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-704cf58 e-con-full e-flex e-con e-child\" data-id=\"704cf58\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f18b2ff e-con-full e-flex e-con e-child\" data-id=\"f18b2ff\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fc277fb elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"fc277fb\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"\u56fe\u50cf\u8f6e\u64ad\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 5\" data-no-translation-aria-label=\"\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"fc277fb\" data-elementor-lightbox-title=\"High-purity UV-Grade Dual-Path Quartz Cuvette for spectroscopy applications\" data-elementor-lightbox-description=\"High-purity UV-Grade Dual-Path Quartz Cuvette for spectroscopy applications\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODczOSwidXJsIjoiaHR0cHM6XC9cL3RvcXVhcnR6LmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDhcL0hpZ2gtcHVyaXR5LVVWLUdyYWRlLUR1YWwtUGF0aC1RdWFydHotQ3V2ZXR0ZS1mb3Itc3BlY3Ryb3Njb3B5LWFwcGxpY2F0aW9ucy53ZWJwIiwic2xpZGVzaG93IjoiZmMyNzdmYiJ9\" href=\"https:\/\/toquartz.com\/wp-content\/uploads\/2025\/08\/High-purity-UV-Grade-Dual-Path-Quartz-Cuvette-for-spectroscopy-applications.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/toquartz.com\/wp-content\/uploads\/2025\/08\/High-purity-UV-Grade-Dual-Path-Quartz-Cuvette-for-spectroscopy-applications.webp\" alt=\"Hochreine UV-Grade-Doppelweg-Quarzk\u00fcvette f\u00fcr Spektroskopieanwendungen\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 5\" data-no-translation-aria-label=\"\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"fc277fb\" data-elementor-lightbox-title=\"UV-Grade Dual-Path Quartz Cuvettes with \u226599.98% SiO\u2082 purity\" data-elementor-lightbox-description=\"UV-Grade Dual-Path Quartz Cuvettes with \u226599.98% SiO\u2082 purity\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODczOCwidXJsIjoiaHR0cHM6XC9cL3RvcXVhcnR6LmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDhcL1VWLUdyYWRlLUR1YWwtUGF0aC1RdWFydHotQ3V2ZXR0ZXMtd2l0aC1cdTIyNjU5OS45OC1TaU9cdTIwODItcHVyaXR5LndlYnAiLCJzbGlkZXNob3ciOiJmYzI3N2ZiIn0%3D\" href=\"https:\/\/toquartz.com\/wp-content\/uploads\/2025\/08\/UV-Grade-Dual-Path-Quartz-Cuvettes-with-\u226599.98-SiO\u2082-purity.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/toquartz.com\/wp-content\/uploads\/2025\/08\/UV-Grade-Dual-Path-Quartz-Cuvettes-with-\u226599.98-SiO\u2082-purity.webp\" alt=\"UV-Grade-Doppelweg-Quarzk\u00fcvetten mit \u226599,98% SiO\u2082-Reinheit\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 5\" data-no-translation-aria-label=\"\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"fc277fb\" data-elementor-lightbox-title=\"UV-Grade Dual-Path Quartz Cuvette for spectroscopy\" data-elementor-lightbox-description=\"UV-Grade Dual-Path Quartz Cuvette for spectroscopy\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODczNywidXJsIjoiaHR0cHM6XC9cL3RvcXVhcnR6LmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDhcL1VWLUdyYWRlLUR1YWwtUGF0aC1RdWFydHotQ3V2ZXR0ZS1mb3Itc3BlY3Ryb3Njb3B5LndlYnAiLCJzbGlkZXNob3ciOiJmYzI3N2ZiIn0%3D\" href=\"https:\/\/toquartz.com\/wp-content\/uploads\/2025\/08\/UV-Grade-Dual-Path-Quartz-Cuvette-for-spectroscopy.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/toquartz.com\/wp-content\/uploads\/2025\/08\/UV-Grade-Dual-Path-Quartz-Cuvette-for-spectroscopy.webp\" alt=\"UV-Grade-Doppelweg-Quarzk\u00fcvette f\u00fcr die Spektroskopie\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 5\" data-no-translation-aria-label=\"\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"fc277fb\" data-elementor-lightbox-title=\"Precision-engineered UV-Grade Dual-Path Quartz Cuvettes\" data-elementor-lightbox-description=\"Precision-engineered UV-Grade Dual-Path Quartz Cuvettes\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODczNiwidXJsIjoiaHR0cHM6XC9cL3RvcXVhcnR6LmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDhcL1ByZWNpc2lvbi1lbmdpbmVlcmVkLVVWLUdyYWRlLUR1YWwtUGF0aC1RdWFydHotQ3V2ZXR0ZXMud2VicCIsInNsaWRlc2hvdyI6ImZjMjc3ZmIifQ%3D%3D\" href=\"https:\/\/toquartz.com\/wp-content\/uploads\/2025\/08\/Precision-engineered-UV-Grade-Dual-Path-Quartz-Cuvettes.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/toquartz.com\/wp-content\/uploads\/2025\/08\/Precision-engineered-UV-Grade-Dual-Path-Quartz-Cuvettes.webp\" alt=\"Pr\u00e4zisionsgefertigte UV-Grade-Doppelweg-Quarzk\u00fcvetten\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 5\" data-no-translation-aria-label=\"\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"fc277fb\" data-elementor-lightbox-title=\"Precision-engineered optical cells for accurate UV-Vis spectroscopy measurement\" data-elementor-lightbox-description=\"Precision-engineered optical cells for accurate UV-Vis spectroscopy measurement\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODczNSwidXJsIjoiaHR0cHM6XC9cL3RvcXVhcnR6LmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDhcL1ByZWNpc2lvbi1lbmdpbmVlcmVkLW9wdGljYWwtY2VsbHMtZm9yLWFjY3VyYXRlLVVWLVZpcy1zcGVjdHJvc2NvcHktbWVhc3VyZW1lbnQud2VicCIsInNsaWRlc2hvdyI6ImZjMjc3ZmIifQ%3D%3D\" href=\"https:\/\/toquartz.com\/wp-content\/uploads\/2025\/08\/Precision-engineered-optical-cells-for-accurate-UV-Vis-spectroscopy-measurement.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/toquartz.com\/wp-content\/uploads\/2025\/08\/Precision-engineered-optical-cells-for-accurate-UV-Vis-spectroscopy-measurement.webp\" alt=\"Pr\u00e4zisionsgefertigte optische Zellen f\u00fcr genaue UV-Vis-Spektroskopiemessungen\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0aec0e7 e-con-full e-flex e-con e-child\" data-id=\"0aec0e7\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7f93d1b e-con-full e-flex e-con e-child\" data-id=\"7f93d1b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-664db70 elementor-widget elementor-widget-heading\" data-id=\"664db70\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Spectral-Flat Custom UV-Grade Dual-Path Quarzk\u00fcvette f\u00fcr UV-Vis Anwendungen -TOQUARTZ\u00ae<\/h1>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d45f7e0 e-con-full e-flex e-con e-child\" data-id=\"d45f7e0\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0670f90 elementor-widget elementor-widget-text-editor\" data-id=\"0670f90\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tDie TOQUARTZ\u00ae UV-Grade Dual-Path Quarzk\u00fcvette ist eine hochreine optische Zelle, die f\u00fcr UV-Vis-Spektroskopie-Anwendungen entwickelt wurde. Sie besteht aus \u226599,98% SiO\u2082-Quarzglas und bietet eine hervorragende Transmission im Wellenl\u00e4ngenbereich von 190-2500nm ohne Absorptionsspitzen. Das Zweipfad-Design sorgt f\u00fcr eine genaue Ausrichtung des Lichtweges und ist somit ideal f\u00fcr Spektrophotometer, Fluoreszenzanalysatoren und medizinische Diagnoseger\u00e4te.\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7862a1f e-con-full e-flex e-con e-child\" data-id=\"7862a1f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cc31700 elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"cc31700\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-bob\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjczNyIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Angebot anfordern<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b27e459 elementor-align-left get-pdf elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"b27e459\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-bob\" href=\"https:\/\/toquartz.com\/wp-content\/uploads\/2025\/08\/TOQUARTZ\u00ae-UV-Grade-Dual-Path-Quartz-Cuvette.pdf\" pdf=\"https:\/\/toquartz.com\/wp-content\/uploads\/2025\/04\/TOQUARTZ-CATALOG-Quartz-Tube.pdf\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-file-download\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Katalog herunterladen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-099d8c2 e-con-full e-flex e-con e-child\" data-id=\"099d8c2\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-961fc63 e-con-full e-flex e-con e-child\" data-id=\"961fc63\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9d603f1 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"9d603f1\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-square\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e6a1f7d elementor-widget elementor-widget-text-editor\" data-id=\"e6a1f7d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tKein MOQ\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e1ec9b3 e-con-full e-flex e-con e-child\" data-id=\"e1ec9b3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-81b632d elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"81b632d\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-tools\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77935e2 elementor-widget elementor-widget-text-editor\" data-id=\"77935e2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tKundenspezifisches Design\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-07f00ac e-con-full e-flex e-con e-child\" data-id=\"07f00ac\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-91c35ff elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"91c35ff\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-truck\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55d8698 elementor-widget elementor-widget-text-editor\" data-id=\"55d8698\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tFabrik direkt\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-774922b e-con-full e-flex e-con e-child\" data-id=\"774922b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dc47aa6 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"dc47aa6\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-users\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ada2b0 elementor-widget elementor-widget-text-editor\" data-id=\"2ada2b0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tTechnische Unterst\u00fctzung\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6237895 e-flex e-con-boxed e-con e-parent\" data-id=\"6237895\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-634404b e-con-full e-flex e-con e-child\" data-id=\"634404b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ed7908 e-n-tabs-mobile elementor-widget elementor-widget-n-tabs\" data-id=\"7ed7908\" data-element_type=\"widget\" data-settings=\"{&quot;tabs_justify_horizontal&quot;:&quot;start&quot;,&quot;horizontal_scroll&quot;:&quot;disable&quot;}\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"133003528\" aria-label=\"Pesta\u00f1as. Abre elementos con Intro o Espacio, ci\u00e9rralos con Escape y navega con las Flechas.\" data-no-translation-aria-label=\"\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t<button id=\"e-n-tab-title-1330035281\" data-tab-title-id=\"e-n-tab-title-1330035281\" class=\"e-n-tab-title elementor-animation-bob\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-1330035281\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i>\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i>\t\t<\/span>\n\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tBeschreibung\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1330035282\" data-tab-title-id=\"e-n-tab-title-1330035282\" class=\"e-n-tab-title elementor-animation-bob\" aria-selected=\"false\" data-tab-index=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1330035282\" style=\"--n-tabs-title-order: 2;\">\n\t\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i>\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i>\t\t<\/span>\n\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tLeitlinien f\u00fcr die Verwendung\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div id=\"e-n-tab-content-1330035281\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1330035281\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-24b64a7 e-con-full e-flex e-con e-child\" data-id=\"24b64a7\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ec13896 elementor-widget elementor-widget-heading\" data-id=\"ec13896\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Merkmale der UV-Grade Dual-Path Quarzk\u00fcvette<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-181e02d elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"181e02d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>TOQUARTZ\u00ae UV-Grade Dual-Path Quarzk\u00fcvetten werden aus hochwertigem Quarzglas hergestellt, das eine hervorragende optische Leistung und Haltbarkeit f\u00fcr Ihre spektroskopischen Anwendungen gew\u00e4hrleistet. Jede K\u00fcvette wird sorgf\u00e4ltig nach genauen Spezifikationen gefertigt und unterliegt strengen Qualit\u00e4tskontrollen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1195a5b e-flex e-con-boxed e-con e-child\" data-id=\"1195a5b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7d5ec5d e-con-full e-flex e-con e-child\" data-id=\"7d5ec5d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e060cf3 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"e060cf3\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-cube\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMaterialzusammensetzung\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb1ca6e elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"eb1ca6e\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Hochreines Quarzglas (\u226599,98% SiO\u2082)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Hohe thermische Stabilit\u00e4t (bis zu 1100\u00b0C)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ausgezeichnete chemische Best\u00e4ndigkeit gegen S\u00e4uren, Basen und Salzl\u00f6sungen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Niedriger W\u00e4rmeausdehnungskoeffizient (5,5\u00d710-\u2077 \/\u00b0C)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3d3c88 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"e3d3c88\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-lightbulb\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tOptische Leistung\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3e5602 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b3e5602\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Hohe UV-Durchl\u00e4ssigkeit (&gt;80% bei 190-250nm)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Keine Absorptionsspitzen im Bereich 200-2500nm<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ebenheit der optischen Oberfl\u00e4che \u2264\u03bb\/4<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Zweipfad-Konstruktion gew\u00e4hrleistet konsistente Ausrichtung des Lichtweges<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8349421 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"8349421\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-tools\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPr\u00e4zisionsfertigung\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba021cf elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"ba021cf\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Enge Abmessungstoleranzen (\u00b10,1 mm)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Polieren in optischer Qualit\u00e4t f\u00fcr klare, blasenfreie Oberfl\u00e4chen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Kratzfreie Oberfl\u00e4chen f\u00fcr optimale Lichtdurchl\u00e4ssigkeit<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Gleichm\u00e4\u00dfige Wandst\u00e4rke f\u00fcr einheitliche optische Eigenschaften<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b48d8cc e-con-full e-flex e-con e-child\" data-id=\"b48d8cc\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a39a2bc elementor-widget elementor-widget-image\" data-id=\"a39a2bc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/toquartz.com\/wp-content\/uploads\/elementor\/thumbs\/Precision-engineered-optical-cells-for-accurate-UV-Vis-spectroscopy-measurement-r9st4bir2rnexsc511waoljdu5g125jrgxurl855zc.webp\" title=\"Pr\u00e4zisionsgefertigte optische Zellen f\u00fcr genaue UV-Vis-Spektroskopiemessungen\" alt=\"Pr\u00e4zisionsgefertigte optische Zellen f\u00fcr genaue UV-Vis-Spektroskopiemessungen\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3dbb5ff e-con-full e-flex e-con e-child\" data-id=\"3dbb5ff\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0596690 elementor-widget elementor-widget-text-editor\" data-id=\"0596690\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tTOQUARTZ\u00ae UV-Grade-Zweipfad-Quarzk\u00fcvette\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f9da87d e-con-full e-flex e-con e-child\" data-id=\"f9da87d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8403afb elementor-mobile-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8403afb\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-cube\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Anpassbare Kammervolumina<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2b64db elementor-mobile-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a2b64db\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-shield-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Verschiedene geometrische Konfigurationen verf\u00fcgbar<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9552916 elementor-mobile-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9552916\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-pencil-ruler\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mehrere Optionen f\u00fcr die Pfadl\u00e4nge<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fbb79a9 e-con-full e-flex e-con e-child\" data-id=\"fbb79a9\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4348bbe e-con-full e-flex e-con e-child\" data-id=\"4348bbe\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f3bfde7 elementor-widget elementor-widget-heading\" data-id=\"f3bfde7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Technische Daten und Abmessungen der UV-Grade Dual-Path Quarzk\u00fcvette<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad869ff elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"ad869ff\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tTOQUARTZ\u00ae UV-Grade Dual-Path-Quarzk\u00fcvetten werden nach pr\u00e4zisen Spezifikationen hergestellt, die eine gleichbleibende Leistung in allen Analyseger\u00e4ten gew\u00e4hrleisten. Im Folgenden finden Sie die detaillierten technischen Parameter, die unsere Produktqualit\u00e4t definieren.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67eadc5 elementor-widget elementor-widget-heading\" data-id=\"67eadc5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Technische Daten<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb03895 tb elementor-widget elementor-widget-text-editor\" data-id=\"fb03895\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" width=\"1143\" height=\"396\" style=\"border-collapse:collapse;width:857.27pt;\">\n<colgroup>\n<col width=\"381\" style=\"width:285.75pt;\" span=\"3\">\n <\/colgroup>\n<tbody>\n<tr height=\"18\" style=\"height:13.50pt;\">\n<td height=\"18\" width=\"381\" x:str=\"\" style=\"height:13.50pt;width:285.75pt;\">Eigentum<\/td>\n<td width=\"381\" x:str=\"\" style=\"width:285.75pt;\">Spezifikation<\/td>\n<td width=\"381\" x:str=\"\" style=\"width:285.75pt;\">Pr\u00fcfverfahren<\/td>\n<\/tr>\n<tr height=\"18\" style=\"height:13.50pt;\">\n<td colspan=\"3\" height=\"18\" x:str=\"\" style=\"height:13.50pt;\"><b>1. Physikalische Eigenschaften<\/b><\/td>\n<\/tr>\n<tr height=\"18\" style=\"height:13.50pt;\">\n<td height=\"18\" x:str=\"\" style=\"height:13.50pt;\">Material<\/td>\n<td x:str=\"\">Geschmolzener Quarz (\u226599.98% SiO\u2082)<\/td>\n<td x:str=\"\">XRF-Analyse<\/td>\n<\/tr>\n<tr height=\"18\" style=\"height:13.50pt;\">\n<td height=\"18\" x:str=\"\" style=\"height:13.50pt;\">Dichte<\/td>\n<td x:str=\"\">2,2 g\/cm\u00b3<\/td>\n<td x:str=\"\">ASTM C693<\/td>\n<\/tr>\n<tr height=\"18\" style=\"height:13.50pt;\">\n<td height=\"18\" x:str=\"\" style=\"height:13.50pt;\">Abmessungstoleranz<\/td>\n<td x:str=\"\">\u00b10,1mm<\/td>\n<td x:str=\"\">Digitales Mikrometer<\/td>\n<\/tr>\n<tr height=\"18\" style=\"height:13.50pt;\">\n<td height=\"18\" x:str=\"\" style=\"height:13.50pt;\">Gleichm\u00e4\u00dfigkeit der Wanddicke<\/td>\n<td x:str=\"\">\u00b10,1mm<\/td>\n<td x:str=\"\">Digitales Mikrometer<\/td>\n<\/tr>\n<tr height=\"18\" style=\"height:13.50pt;\">\n<td height=\"18\" x:str=\"\" style=\"height:13.50pt;\">Oberfl\u00e4che<\/td>\n<td x:str=\"\">Optische Politur<\/td>\n<td x:str=\"\">Visuelle Inspektion<\/td>\n<\/tr>\n<tr height=\"18\" style=\"height:13.50pt;\">\n<td height=\"18\" x:str=\"\" style=\"height:13.50pt;\">Maximale Betriebstemperatur<\/td>\n<td x:str=\"\">1100\u00b0C<\/td>\n<td x:str=\"\">Thermische Pr\u00fcfung<\/td>\n<\/tr>\n<tr height=\"18\" style=\"height:13.50pt;\">\n<td height=\"18\" x:str=\"\" style=\"height:13.50pt;\">W\u00e4rmeausdehnungskoeffizient<\/td>\n<td x:str=\"\">5.5\u00d710-\u2077 \/\u00b0C<\/td>\n<td x:str=\"\">ASTM E228<\/td>\n<\/tr>\n<tr height=\"18\" style=\"height:13.50pt;\">\n<td colspan=\"3\" height=\"18\" x:str=\"\" style=\"height:13.50pt;\"><b>2. Optische Eigenschaften<\/b><\/td>\n<\/tr>\n<tr height=\"18\" style=\"height:13.50pt;\">\n<td height=\"18\" x:str=\"\" style=\"height:13.50pt;\">\u00dcbertragungsbereich<\/td>\n<td x:str=\"\">200-2500nm<\/td>\n<td x:str=\"\">UV-Vis-NIR-Spektrophotometer<\/td>\n<\/tr>\n<tr height=\"18\" style=\"height:13.50pt;\">\n<td height=\"18\" x:str=\"\" style=\"height:13.50pt;\">UV-Durchl\u00e4ssigkeit (200-250nm)<\/td>\n<td x:str=\"\">&gt;80% (gepaarte Tests)<\/td>\n<td x:str=\"\">UV-Vis-Spektrophotometer<\/td>\n<\/tr>\n<tr height=\"18\" style=\"height:13.50pt;\">\n<td height=\"18\" x:str=\"\" style=\"height:13.50pt;\">Optische Oberfl\u00e4chenebenheit<\/td>\n<td x:str=\"\">\u2264\u03bb\/4<\/td>\n<td x:str=\"\">Interferometer<\/td>\n<\/tr>\n<tr height=\"18\" style=\"height:13.50pt;\">\n<td height=\"18\" x:str=\"\" style=\"height:13.50pt;\">Brechungsindex (589,3nm)<\/td>\n<td x:num=\"1.4585\" align=\"right\">1.4585<\/td>\n<td x:str=\"\">Refraktometer<\/td>\n<\/tr>\n<tr height=\"18\" style=\"height:13.50pt;\">\n<td height=\"18\" x:str=\"\" style=\"height:13.50pt;\">Qualit\u00e4t der Oberfl\u00e4che<\/td>\n<td x:str=\"\">Kratzfrei, blasenfrei<\/td>\n<td x:str=\"\">Visuelle Inspektion (10X)<\/td>\n<\/tr>\n<tr height=\"18\" style=\"height:13.50pt;\">\n<td height=\"18\" x:str=\"\" style=\"height:13.50pt;\">Genauigkeit der Pfadl\u00e4nge<\/td>\n<td x:str=\"\">\u00b10,01 mm<\/td>\n<td x:str=\"\">Digitales Mikrometer<\/td>\n<\/tr>\n<tr height=\"18\" style=\"height:13.50pt;\">\n<td colspan=\"3\" height=\"18\" x:str=\"\" style=\"height:13.50pt;\"><b>3. Chemische Eigenschaften<\/b><\/td>\n<\/tr>\n<tr height=\"18\" style=\"height:13.50pt;\">\n<td height=\"18\" x:str=\"\" style=\"height:13.50pt;\">Chemische Zusammensetzung<\/td>\n<td x:str=\"\">\u226599.98% SiO\u2082<\/td>\n<td x:str=\"\">XRF-Analyse<\/td>\n<\/tr>\n<tr height=\"18\" style=\"height:13.50pt;\">\n<td height=\"18\" x:str=\"\" style=\"height:13.50pt;\">S\u00e4urebest\u00e4ndigkeit<\/td>\n<td x:str=\"\">Ausgezeichnet (au\u00dfer HF)<\/td>\n<td x:str=\"\">Pr\u00fcfung auf chemische Exposition<\/td>\n<\/tr>\n<tr height=\"18\" style=\"height:13.50pt;\">\n<td height=\"18\" x:str=\"\" style=\"height:13.50pt;\">Alkalibest\u00e4ndigkeit<\/td>\n<td x:str=\"\">Sehr gut<\/td>\n<td x:str=\"\">Pr\u00fcfung auf chemische Exposition<\/td>\n<\/tr>\n<tr height=\"18\" style=\"height:13.50pt;\">\n<td height=\"18\" x:str=\"\" style=\"height:13.50pt;\">L\u00f6semittelbest\u00e4ndigkeit<\/td>\n<td x:str=\"\">Ausgezeichnet<\/td>\n<td x:str=\"\">Pr\u00fcfung auf chemische Exposition<\/td>\n<\/tr>\n<tr height=\"18\" style=\"height:13.50pt;\">\n<td height=\"18\" x:str=\"\" style=\"height:13.50pt;\">Wasserabsorption<\/td>\n<td x:str=\"\">Null<\/td>\n<td x:str=\"\">ASTM C1285<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2583592 e-flex e-con-boxed e-con e-child\" data-id=\"2583592\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-52eb0a6 elementor-widget elementor-widget-heading\" data-id=\"52eb0a6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Gr\u00f6\u00dfentabelle<\/h3>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8f71f32 e-con-full e-flex e-con e-child\" data-id=\"8f71f32\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-5ab9df0 e-con-full e-flex e-con e-child\" data-id=\"5ab9df0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9fa3850 elementor-widget elementor-widget-image\" data-id=\"9fa3850\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/toquartz.com\/wp-content\/uploads\/elementor\/thumbs\/70\u03bcl-UV-Quartz-Cuvette-Sample-Cell-with-Path-Length-0.2mm-r9suiz1mrfm18w0sdkdeivsg4u4hsz0cr8nzkabrp8.webp\" title=\"70\u03bcl UV-Quarzk\u00fcvette Probenzelle mit Schichtdicke 0,2mm\" alt=\"70\u03bcl UV-Quarzk\u00fcvette Probenzelle mit Schichtdicke 0,2mm\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-842580e e-con-full e-flex e-con e-child\" data-id=\"842580e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9a0b3a1 tb elementor-widget elementor-widget-text-editor\" data-id=\"9a0b3a1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" width=\"776\" height=\"108\" style=\"border-collapse:collapse;width:582.02pt;\">\n <colgroup><col width=\"101\" style=\"width:75.75pt;\">\n <col width=\"178\" style=\"width:133.50pt;\">\n <col width=\"109\" style=\"width:81.75pt;\">\n <col width=\"69\" style=\"width:51.75pt;\" span=\"2\">\n <col width=\"101\" style=\"width:75.75pt;\">\n <col width=\"149\" style=\"width:111.75pt;\">\n <\/colgroup><tbody><tr height=\"22\" style=\"height:16.50pt;\">\n  <td class=\"et3\" height=\"22\" width=\"101\" x:str=\"\" style=\"height:16.50pt;width:75.75pt;\">Modell<\/td>\n  <td class=\"et4\" width=\"178\" x:str=\"\" style=\"width:133.50pt;\">Beschreibung<\/td>\n  <td class=\"et4\" width=\"109\" x:str=\"\" style=\"width:81.75pt;\">Wellenl\u00e4nge<\/td>\n  <td class=\"et4\" width=\"69\" x:str=\"\" style=\"width:51.75pt;\">Pfadl\u00e4nge<\/td>\n  <td class=\"et4\" width=\"69\" x:str=\"\" style=\"width:51.75pt;\">Band<\/td>\n  <td class=\"et4\" width=\"101\" x:str=\"\" style=\"width:75.75pt;\">Durchl\u00e4ssigkeit<\/td>\n  <td class=\"et4\" width=\"149\" x:str=\"\" style=\"width:111.75pt;\">Umriss Dimension<\/td>\n <\/tr>\n <tr height=\"86\" style=\"height:65.00pt;\">\n  <td class=\"et5\" height=\"86\" x:str=\"\" style=\"height:65.00pt;\">AT-BSM-025<\/td>\n  <td class=\"et6\" width=\"178\" x:str=\"\" style=\"width:133.50pt;\">70\u03bcl UV-Quarzk\u00fcvette Probenzelle mit Schichtdicke 0,2mm<\/td>\n  <td class=\"et7\" width=\"109\" x:str=\"\" style=\"width:81.75pt;\">200nm-2500nm<\/td>\n  <td class=\"et7\" width=\"69\" x:str=\"\" style=\"width:51.75pt;\">0,2 mm<\/td>\n  <td class=\"et7\" width=\"69\" x:str=\"\" style=\"width:51.75pt;\">70\u03bcl<\/td>\n  <td class=\"et7\" width=\"101\" x:str=\"\" style=\"width:75.75pt;\">&gt;80% (gepaarte Tests)<\/td>\n  <td class=\"et7\" width=\"149\" x:str=\"\" style=\"width:111.75pt;\">12,5\u00d72,7\u00d745 mm<\/td>\n <\/tr>\n<\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5d93a9b e-con-full e-flex e-con e-child\" data-id=\"5d93a9b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-6a68eee e-con-full e-flex e-con e-child\" data-id=\"6a68eee\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-efbc4bb elementor-widget elementor-widget-image\" data-id=\"efbc4bb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/toquartz.com\/wp-content\/uploads\/elementor\/thumbs\/250\u03bcl-UV-Grade-Dual-Path-Quartz-Cuvette-r9sukazefzfnp035ln3dk1oyfhk7pjanxtxr1ecovw.webp\" title=\"250\u03bcl UV-Doppelweg-K\u00fcvette aus Quarz\" alt=\"250\u03bcl UV-Doppelweg-K\u00fcvette aus Quarz\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0770070 e-con-full e-flex e-con e-child\" data-id=\"0770070\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-709c3b3 tb elementor-widget elementor-widget-text-editor\" data-id=\"709c3b3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" width=\"776\" height=\"108\" style=\"border-collapse:collapse;width:582.02pt;\">\n <colgroup><col width=\"101\" style=\"width:75.75pt;\">\n <col width=\"178\" style=\"width:133.50pt;\">\n <col width=\"109\" style=\"width:81.75pt;\">\n <col width=\"69\" style=\"width:51.75pt;\" span=\"2\">\n <col width=\"101\" style=\"width:75.75pt;\">\n <col width=\"149\" style=\"width:111.75pt;\">\n <\/colgroup><tbody><tr height=\"22\" style=\"height:16.50pt;\">\n  <td class=\"et3\" height=\"22\" width=\"101\" x:str=\"\" style=\"height:16.50pt;width:75.75pt;\">Modell<\/td>\n  <td class=\"et4\" width=\"178\" x:str=\"\" style=\"width:133.50pt;\">Beschreibung<\/td>\n  <td class=\"et4\" width=\"109\" x:str=\"\" style=\"width:81.75pt;\">Wellenl\u00e4nge<\/td>\n  <td class=\"et4\" width=\"69\" x:str=\"\" style=\"width:51.75pt;\">Pfadl\u00e4nge<\/td>\n  <td class=\"et4\" width=\"69\" x:str=\"\" style=\"width:51.75pt;\">Band<\/td>\n  <td class=\"et4\" width=\"101\" x:str=\"\" style=\"width:75.75pt;\">Durchl\u00e4ssigkeit<\/td>\n  <td class=\"et4\" width=\"149\" x:str=\"\" style=\"width:111.75pt;\">Umriss Dimension<\/td>\n <\/tr>\n <tr height=\"86\" style=\"height:65.00pt;\">\n  <td class=\"et5\" height=\"86\" x:str=\"\" style=\"height:65.00pt;\">AT-BSM-043<\/td>\n  <td class=\"et6\" width=\"178\" x:str=\"\" style=\"width:133.50pt;\">250\u03bcl UV-Doppelweg-K\u00fcvette aus Quarz<\/td>\n  <td class=\"et7\" width=\"109\" x:str=\"\" style=\"width:81.75pt;\">200nm-2500nm<\/td>\n  <td class=\"et7\" width=\"69\" x:str=\"\" style=\"width:51.75pt;\">5 mm<\/td>\n  <td class=\"et7\" width=\"69\" x:str=\"\" style=\"width:51.75pt;\">250\u03bcl<\/td>\n  <td class=\"et7\" width=\"101\" x:str=\"\" style=\"width:75.75pt;\">&gt;80% (gepaarte Tests)<\/td>\n  <td class=\"et7\" width=\"149\" x:str=\"\" style=\"width:111.75pt;\">7x7x15mm<\/td>\n <\/tr>\n<\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-33f8f74 e-con-full e-flex e-con e-child\" data-id=\"33f8f74\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-c53b6fc e-con-full e-flex e-con e-child\" data-id=\"c53b6fc\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f0df8a0 elementor-widget elementor-widget-image\" data-id=\"f0df8a0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/toquartz.com\/wp-content\/uploads\/elementor\/thumbs\/7ml-UV-Grade-Dual-Path-Quartz-Cuvette-r9sul9rfgur9mkomyk4kmax0eqssmc4qem2psmx4ho.webp\" title=\"7ml UV-Grade-Zweipfad-Quarzk\u00fcvette\" alt=\"7ml UV-Grade-Zweipfad-Quarzk\u00fcvette\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e12a8d e-con-full e-flex e-con e-child\" data-id=\"5e12a8d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a977f40 tb elementor-widget elementor-widget-text-editor\" data-id=\"a977f40\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" width=\"776\" height=\"108\" style=\"border-collapse:collapse;width:582.02pt;\">\n <colgroup><col width=\"101\" style=\"width:75.75pt;\">\n <col width=\"178\" style=\"width:133.50pt;\">\n <col width=\"109\" style=\"width:81.75pt;\">\n <col width=\"69\" style=\"width:51.75pt;\" span=\"2\">\n <col width=\"101\" style=\"width:75.75pt;\">\n <col width=\"149\" style=\"width:111.75pt;\">\n <\/colgroup><tbody><tr height=\"22\" style=\"height:16.50pt;\">\n  <td class=\"et3\" height=\"22\" width=\"101\" x:str=\"\" style=\"height:16.50pt;width:75.75pt;\">Modell<\/td>\n  <td class=\"et4\" width=\"178\" x:str=\"\" style=\"width:133.50pt;\">Beschreibung<\/td>\n  <td class=\"et4\" width=\"109\" x:str=\"\" style=\"width:81.75pt;\">Wellenl\u00e4nge<\/td>\n  <td class=\"et4\" width=\"69\" x:str=\"\" style=\"width:51.75pt;\">Pfadl\u00e4nge<\/td>\n  <td class=\"et4\" width=\"69\" x:str=\"\" style=\"width:51.75pt;\">Band<\/td>\n  <td class=\"et4\" width=\"101\" x:str=\"\" style=\"width:75.75pt;\">Durchl\u00e4ssigkeit<\/td>\n  <td class=\"et4\" width=\"149\" x:str=\"\" style=\"width:111.75pt;\">Umriss Dimension<\/td>\n <\/tr>\n <tr height=\"86\" style=\"height:65.00pt;\">\n  <td class=\"et5\" height=\"86\" x:str=\"\" style=\"height:65.00pt;\">AT-BSM-036<\/td>\n  <td class=\"et6\" width=\"178\" x:str=\"\" style=\"width:133.50pt;\">7ml UV-Grade-Zweipfad-Quarzk\u00fcvette<\/td>\n  <td class=\"et7\" width=\"109\" x:str=\"\" style=\"width:81.75pt;\">200nm-2500nm<\/td>\n  <td class=\"et7\" width=\"69\" x:str=\"\" style=\"width:51.75pt;\">5 mm<\/td>\n  <td class=\"et7\" width=\"69\" x:str=\"\" style=\"width:51.75pt;\">7ml<\/td>\n  <td class=\"et7\" width=\"101\" x:str=\"\" style=\"width:75.75pt;\">&gt;80% (gepaarte Tests)<\/td>\n  <td class=\"et7\" width=\"149\" x:str=\"\" style=\"width:111.75pt;\">45x7x45mm<\/td>\n <\/tr>\n<\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6dd7e0f e-con-full e-flex e-con e-child\" data-id=\"6dd7e0f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-f4f782f e-con-full e-flex e-con e-child\" data-id=\"f4f782f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-490665a elementor-widget elementor-widget-image\" data-id=\"490665a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/toquartz.com\/wp-content\/uploads\/elementor\/thumbs\/Standard-UV-Grade-Dual-Path-Quartz-Cuvette-r9sum3u9jjwfy3gy2x4mu3brf2ojgng56qy95hoiyk.webp\" title=\"Standard-UV-Qualit\u00e4ts-Zweipfad-Quarzk\u00fcvette\" alt=\"Standard-UV-Qualit\u00e4ts-Zweipfad-Quarzk\u00fcvette\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eb202aa e-con-full e-flex e-con e-child\" data-id=\"eb202aa\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6a0793f tb elementor-widget elementor-widget-text-editor\" data-id=\"6a0793f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" width=\"776\" height=\"108\" style=\"border-collapse:collapse;width:582.02pt;\">\n <colgroup><col width=\"101\" style=\"width:75.75pt;\">\n <col width=\"178\" style=\"width:133.50pt;\">\n <col width=\"109\" style=\"width:81.75pt;\">\n <col width=\"69\" style=\"width:51.75pt;\" span=\"2\">\n <col width=\"101\" style=\"width:75.75pt;\">\n <col width=\"149\" style=\"width:111.75pt;\">\n <\/colgroup><tbody><tr height=\"22\" style=\"height:16.50pt;\">\n  <td class=\"et3\" height=\"22\" width=\"101\" x:str=\"\" style=\"height:16.50pt;width:75.75pt;\">Modell<\/td>\n  <td class=\"et4\" width=\"178\" x:str=\"\" style=\"width:133.50pt;\">Beschreibung<\/td>\n  <td class=\"et4\" width=\"109\" x:str=\"\" style=\"width:81.75pt;\">Wellenl\u00e4nge<\/td>\n  <td class=\"et4\" width=\"69\" x:str=\"\" style=\"width:51.75pt;\">Pfadl\u00e4nge<\/td>\n  <td class=\"et4\" width=\"69\" x:str=\"\" style=\"width:51.75pt;\">Band<\/td>\n  <td class=\"et4\" width=\"101\" x:str=\"\" style=\"width:75.75pt;\">Durchl\u00e4ssigkeit<\/td>\n  <td class=\"et4\" width=\"149\" x:str=\"\" style=\"width:111.75pt;\">Umriss Dimension<\/td>\n <\/tr>\n <tr height=\"86\" style=\"height:65.00pt;\">\n  <td class=\"et5\" height=\"86\" x:str=\"\" style=\"height:65.00pt;\">AT-BSM-060<\/td>\n  <td class=\"et6\" width=\"178\" x:str=\"\" style=\"width:133.50pt;\">Standard-UV-Qualit\u00e4ts-Zweipfad-Quarzk\u00fcvette<\/td>\n  <td class=\"et7\" width=\"109\" x:str=\"\" style=\"width:81.75pt;\">200nm-2500nm<\/td>\n  <td class=\"et7\" width=\"69\" x:str=\"\" style=\"width:51.75pt;\">10mm<\/td>\n  <td class=\"et7\" width=\"69\" x:str=\"\" style=\"width:51.75pt;\">\/<\/td>\n  <td class=\"et7\" width=\"101\" x:str=\"\" style=\"width:75.75pt;\">&gt;80% (gepaarte Tests)<\/td>\n  <td class=\"et7\" width=\"149\" x:str=\"\" style=\"width:111.75pt;\">12,5\u00d712,5x44mm<\/td>\n <\/tr>\n<\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2c8f008 e-con-full e-flex e-con e-child\" data-id=\"2c8f008\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2a44cdb elementor-widget elementor-widget-text-editor\" data-id=\"2a44cdb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tHinweis: Wir bieten kundenspezifische Spezifikationen an, um Ihre spezifischen Anforderungen zu erf\u00fcllen. Kontaktieren Sie unser Ingenieurteam f\u00fcr eine Beratung.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e16ccce elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e16ccce\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-bob\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjczNyIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Gesendete kundenspezifische Anforderungen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cc42b2b e-con-full e-flex e-con e-child\" data-id=\"cc42b2b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b635990 elementor-widget elementor-widget-heading\" data-id=\"b635990\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">TOQUARTZ\u00ae l\u00f6st Herausforderungen mit UV-Doppelweg-Quarzk\u00fcvette<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f6ba871 e-con-full e-flex e-con e-child\" data-id=\"f6ba871\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d0e9172 e-n-tabs-mobile elementor-widget elementor-widget-n-tabs\" data-id=\"d0e9172\" data-element_type=\"widget\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"219058546\" aria-label=\"Pesta\u00f1as. Abre elementos con Intro o Espacio, ci\u00e9rralos con Escape y navega con las Flechas.\" data-no-translation-aria-label=\"\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t<button id=\"e-n-tab-title-2190585461\" data-tab-title-id=\"e-n-tab-title-2190585461\" class=\"e-n-tab-title elementor-animation-bob\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-2190585461\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t<\/span>\n\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tAnalytische Instrumentierung\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-2190585462\" data-tab-title-id=\"e-n-tab-title-2190585462\" class=\"e-n-tab-title elementor-animation-bob\" aria-selected=\"false\" data-tab-index=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-2190585462\" style=\"--n-tabs-title-order: 2;\">\n\t\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t<\/span>\n\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tMedizinische Diagnostik\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-2190585463\" data-tab-title-id=\"e-n-tab-title-2190585463\" class=\"e-n-tab-title elementor-animation-bob\" aria-selected=\"false\" data-tab-index=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-2190585463\" style=\"--n-tabs-title-order: 3;\">\n\t\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t<\/span>\n\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tUmweltanalyse\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div id=\"e-n-tab-content-2190585461\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-2190585461\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-2de9501 e-con-full e-flex e-con e-child\" data-id=\"2de9501\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c16dba2 e-con-full e-flex e-con e-child\" data-id=\"c16dba2\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-28c220a e-con-full e-flex e-con e-child\" data-id=\"28c220a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d799fa7 elementor-widget elementor-widget-heading\" data-id=\"d799fa7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">UV-Doppelweg-Quarzk\u00fcvetten in analytischen Instrumenten<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52e4835 elementor-widget elementor-widget-text-editor\" data-id=\"52e4835\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tHersteller von Analyseger\u00e4ten ben\u00f6tigen K\u00fcvetten mit pr\u00e4zisen Abmessungstoleranzen und optischen Eigenschaften, um genaue und reproduzierbare Messungen zu gew\u00e4hrleisten. Inkonsistente optische Pfadl\u00e4ngen oder Oberfl\u00e4chenfehler k\u00f6nnen zu erheblichen Messfehlern f\u00fchren, die die Leistung und Zuverl\u00e4ssigkeit der Instrumente beeintr\u00e4chtigen. Unsere Dual-Path-K\u00fcvetten wurden speziell entwickelt, um eine gleichbleibende Pfadl\u00e4ngengenauigkeit \u00fcber alle Produktionschargen hinweg zu gew\u00e4hrleisten und eine zuverl\u00e4ssige Integration mit Spektralphotometern und anderen Analyseger\u00e4ten sicherzustellen.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ca7afa9 e-con-full e-flex e-con e-child\" data-id=\"ca7afa9\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-76aa23d e-con-full e-flex e-con e-child\" data-id=\"76aa23d\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50d499d elementor-widget elementor-widget-heading\" data-id=\"50d499d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Die wichtigsten Vorteile<\/h4>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-89c7795 e-con-full e-flex e-con e-child\" data-id=\"89c7795\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8cf266a elementor-widget-mobile__width-initial elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8cf266a\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-shield-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Submillimeter-Bahnl\u00e4ngen-Genauigkeit<\/b><br> Jede K\u00fcvette hat eine chargen\u00fcbergreifende Toleranz von \u00b10,01 mm in der Schichtdicke, was durch Laserinterferometrie \u00fcberpr\u00fcft wird.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-shield-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Optische Konsistenz von Charge zu Charge<\/b><br> Die Transmissionsabweichung zwischen den Chargen liegt bei \u00b10,5% bei 200-250nm.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-shield-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Instrumentenspezifische Ma\u00dfanpassung<\/b><br> Die Au\u00dfenma\u00dfe sind auf \u00b10,05 mm kalibriert, um einen nahtlosen Anschluss an OEM-Spektralphotometerhalter zu gew\u00e4hrleisten.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12ffb82 elementor-align-center elementor-widget__width-inherit elementor-widget elementor-widget-button\" data-id=\"12ffb82\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-bob\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjczNyIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Meine L\u00f6sung finden<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cbd859e e-con-full e-flex e-con e-child\" data-id=\"cbd859e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1545348 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"1545348\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-stamp\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tTOQUARTZ\u00ae-L\u00f6sung\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEin deutscher Spektralphotometer-OEM meldete eine Fehlerquote von 12% bei der Kalibrierung, die auf inkonsistente K\u00fcvettenabmessungen eines fr\u00fcheren Lieferanten zur\u00fcckzuf\u00fchren war. Nach dem Wechsel zu TOQUARTZ\u00ae Custom UV-Grade Dual-Path Quarzk\u00fcvetten mit einer zertifizierten Pfadl\u00e4nge von \u00b10,01 mm und einer Au\u00dfentoleranz von \u00b10,05 mm sank die Fehlerrate auf unter 1,2%, was zu j\u00e4hrlichen Einsparungen von \u00fcber 38.000 \u20ac f\u00fcr Rekalibrierungs- und Supportkosten f\u00fchrte.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-2190585462\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-2190585462\" data-tab-index=\"2\" style=\"--n-tabs-title-order: 2;\" class=\"elementor-element elementor-element-03f2a37 e-flex e-con-boxed e-con e-child\" data-id=\"03f2a37\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c4481e1 e-con-full e-flex e-con e-child\" data-id=\"c4481e1\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f2247e9 e-con-full e-flex e-con e-child\" data-id=\"f2247e9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e03d07a elementor-widget elementor-widget-heading\" data-id=\"e03d07a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">UV-Doppelweg-K\u00fcvetten aus Quarzglas in der medizinischen Diagnostik<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72295cc elementor-widget elementor-widget-text-editor\" data-id=\"72295cc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tDie Hersteller medizinischer Diagnoseger\u00e4te ben\u00f6tigen K\u00fcvetten mit au\u00dfergew\u00f6hnlicher optischer Klarheit, chemischer Best\u00e4ndigkeit und pr\u00e4zisen Abmessungen f\u00fcr genaue klinische Testergebnisse. Bei diesen Anwendungen werden h\u00e4ufig biologische Proben, die Proteine, Enzyme und andere Biomarker enthalten, mit UV-Absorptions- oder Fluoreszenzverfahren analysiert. Unsere UV-Grade Dual-Path-Quarzk\u00fcvetten bieten die optische Leistung und chemische Stabilit\u00e4t, die f\u00fcr zuverl\u00e4ssige diagnostische Tests im klinischen Umfeld erforderlich sind.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f98779 e-con-full e-flex e-con e-child\" data-id=\"5f98779\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-8eeb1f4 e-con-full e-flex e-con e-child\" data-id=\"8eeb1f4\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6de8b57 elementor-widget elementor-widget-heading\" data-id=\"6de8b57\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Die wichtigsten Vorteile<\/h4>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1649279 e-con-full e-flex e-con e-child\" data-id=\"1649279\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4105268 elementor-widget-mobile__width-initial elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4105268\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-shield-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>UV-Transmissionsstabilit\u00e4t im Proteinbereich<\/b><br> Die Transmission des 82% bei 200-220nm gew\u00e4hrleistet eine genaue Proteinquantifizierung in klinischen Tests.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-shield-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Biofluid-kompatible Oberfl\u00e4chenbeschaffenheit<\/b><br> Die optischen Oberfl\u00e4chen werden auf eine Ebenheit von \u2264\u03bb\/4 poliert und auf Null-Protein-Adsorption bei 24-st\u00fcndiger Exposition gepr\u00fcft.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-shield-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Mikro-Volumen-Pr\u00e4zisionskammern<\/b><br> Kundenspezifische Kammern bis zu 250\u03bcl mit einer Volumentoleranz von \u00b10,01ml f\u00fcr enzymbeschr\u00e4nkte Diagnostik.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3cdcbcd elementor-align-center elementor-widget__width-inherit elementor-widget elementor-widget-button\" data-id=\"3cdcbcd\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-bob\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjczNyIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Meine L\u00f6sung finden<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7eb2c13 e-con-full e-flex e-con e-child\" data-id=\"7eb2c13\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-235833d elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"235833d\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-stamp\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tTOQUARTZ\u00ae-L\u00f6sung\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEin japanischer Hersteller von IVD-Ger\u00e4ten hatte mit uneinheitlichen Absorptionsmesswerten bei Proteintests zu k\u00e4mpfen, die auf die Variabilit\u00e4t der K\u00fcvettenoberfl\u00e4che zur\u00fcckzuf\u00fchren waren. TOQUARTZ\u00ae lieferte paarweise zusammenpassende UV-Grade Dual-Path-Quarzk\u00fcvetten mit zertifizierter UV-Durchl\u00e4ssigkeit und nicht-adsorbierenden Oberfl\u00e4chen, die die Wiederholbarkeit der Tests um 19% verbesserten und falsch-positive Ergebnisse um 22% bei 3.000 Testzyklen reduzierten.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-2190585463\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-2190585463\" data-tab-index=\"3\" style=\"--n-tabs-title-order: 3;\" class=\"elementor-element elementor-element-9414fdd e-flex e-con-boxed e-con e-child\" data-id=\"9414fdd\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9d8eb07 e-con-full e-flex e-con e-child\" data-id=\"9d8eb07\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-747504e e-con-full e-flex e-con e-child\" data-id=\"747504e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f086763 elementor-widget elementor-widget-heading\" data-id=\"f086763\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">UV-Doppelweg-Quarzk\u00fcvetten f\u00fcr die Umweltanalyse<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ffa9b2f elementor-widget elementor-widget-text-editor\" data-id=\"ffa9b2f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLabors f\u00fcr Umweltuntersuchungen ben\u00f6tigen langlebige, chemisch resistente K\u00fcvetten f\u00fcr die Analyse von Wasserqualit\u00e4t, Bodenextrakten und Luftschadstoffen. Diese Anwendungen sind h\u00e4ufig mit aggressiven Chemikalien verbunden und erfordern den Nachweis von Spurenverunreinigungen in sehr geringen Konzentrationen. Unsere UV-Grade Dual-Path-Quarzk\u00fcvetten bieten die chemische Best\u00e4ndigkeit und optische Leistung, die f\u00fcr empfindliche Umweltanalyseanwendungen erforderlich sind.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0d7f5a0 e-con-full e-flex e-con e-child\" data-id=\"0d7f5a0\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5e49875 e-con-full e-flex e-con e-child\" data-id=\"5e49875\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b510bfc elementor-widget elementor-widget-heading\" data-id=\"b510bfc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Die wichtigsten Vorteile<\/h4>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bf55a0f e-con-full e-flex e-con e-child\" data-id=\"bf55a0f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e173ecf elementor-widget-mobile__width-initial elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e173ecf\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-shield-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>S\u00e4ureresistente optische Integrit\u00e4t<\/b><br> Kein Oberfl\u00e4chenabbau nach 1.500 Stunden Einwirkung von pH 2,0 HCl-L\u00f6sung bei 25\u00b0C.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-shield-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Geringe Hintergrundabsorption f\u00fcr Spurendetektion<\/b><br> &lt;0,2% Grundlinienabsorption bei 220 nm erm\u00f6glicht den Nachweis von Schadstoffen im ppb-Bereich.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-shield-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Flow-Through Ready-Anpassung<\/b><br> Unterst\u00fctzt integrierte Einlass-\/Auslassanschl\u00fcsse mit 1,6 mm ID-Schl\u00e4uchen f\u00fcr die Wasser\u00fcberwachung in Echtzeit.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-734104a elementor-align-center elementor-widget__width-inherit elementor-widget elementor-widget-button\" data-id=\"734104a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-bob\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjczNyIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Meine L\u00f6sung finden<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-319e712 e-con-full e-flex e-con e-child\" data-id=\"319e712\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ed64de elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"5ed64de\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-stamp\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tTOQUARTZ\u00ae-L\u00f6sung\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tIn einem kanadischen Wasserqualit\u00e4tslabor kam es nach dreiw\u00f6chiger Einwirkung saurer Proben zu K\u00fcvettenver\u00e4tzungen und Signaldrift. TOQUARTZ\u00ae lieferte s\u00e4urebest\u00e4ndige UV-Grade-Doppelweg-Quarzk\u00fcvetten mit einer Basisabsorption von &lt;0,2% und ohne Oberfl\u00e4chenverschlei\u00df nach 1.500 Stunden Testdauer, was die Lebensdauer der K\u00fcvetten um das 3,7-fache verl\u00e4ngerte und die Ersatzkosten um 68% reduzierte.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2f8cc78 e-con-full e-flex e-con e-child\" data-id=\"2f8cc78\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ac0aefe elementor-widget elementor-widget-heading\" data-id=\"ac0aefe\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Anpassungsdienste f\u00fcr TOQUARTZ\u00ae UV-Grade Dual-Path <br>Quarz-K\u00fcvette<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca03229 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"ca03229\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tTOQUARTZ\u00ae ist spezialisiert auf kundenspezifische UV-Grade Dual-Path Quarzk\u00fcvetten, die auf Ihre spezifischen analytischen Anforderungen zugeschnitten sind. Unser Ingenieurteam arbeitet direkt mit Ihnen zusammen, um K\u00fcvetten zu entwickeln, die sich perfekt in Ihre Instrumente oder Versuchsaufbauten integrieren lassen.\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6c77062 e-grid e-con-boxed e-con e-child\" data-id=\"6c77062\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-df3ba60 e-con-full e-flex e-con e-child\" data-id=\"df3ba60\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-158243d elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"158243d\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-ruler-combined\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tBenutzerdefinierte Abmessungen\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b114364 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b114364\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Nicht standardisierte Pfadl\u00e4ngen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Kundenspezifische Kammervolumen und Geometrien<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Besondere Anforderungen an die Wandst\u00e4rke<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ger\u00e4tespezifische Au\u00dfenma\u00dfe<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e7893e7 e-con-full e-flex e-con e-child\" data-id=\"e7893e7\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1277261 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"1277261\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-puzzle-piece\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tKundenspezifische Tests\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d644aa4 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d644aa4\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Spezifische Wellenl\u00e4ngentransmissionstests<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Verbesserte Berichte zur Dimensionspr\u00fcfung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Validierung der chemischen Vertr\u00e4glichkeit<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Abgestimmte Set-Zertifizierung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-96349d1 e-con-full e-flex e-con e-child\" data-id=\"96349d1\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cbb6935 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"cbb6935\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-tools\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tKundenspezifischer Designprozess\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-270fa6f elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"270fa6f\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-down\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Konsultation: <\/b>Er\u00f6rterung von Anforderungen und technischen Spezifikationen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-down\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Vorschlag f\u00fcr den Entwurf: <\/b>\u00dcberpr\u00fcfung von Detailzeichnungen und Spezifikationen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-down\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Prototyp: <\/b>Herstellung und Pr\u00fcfung von Mustern<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-down\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Validierung: <\/b>Qualit\u00e4tspr\u00fcfung und Zulassung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-down\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Produktion: <\/b>Herstellung und Lieferung in gro\u00dfem Ma\u00dfstab<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-1330035282\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1330035282\" data-tab-index=\"2\" style=\"--n-tabs-title-order: 2;\" class=\"elementor-element elementor-element-e88a21c e-flex e-con-boxed e-con e-child\" data-id=\"e88a21c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b69d22d elementor-widget elementor-widget-heading\" data-id=\"b69d22d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gebrauchsanweisung f\u00fcr die UV-Doppelweg-Quarzk\u00fcvette<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-639eb57 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"639eb57\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tDie richtige Handhabung, Verwendung und Wartung von UV-Grade Dual-Path-Quarzk\u00fcvetten gew\u00e4hrleistet optimale Leistung und eine lange Lebensdauer. Die folgenden Richtlinien werden Ihnen helfen, den Wert Ihrer Investition zu maximieren.\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-06c4a8a e-grid e-con-full e-con e-child\" data-id=\"06c4a8a\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-81c2391 e-con-full e-flex e-con e-child\" data-id=\"81c2391\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e3d15cd e-con-full e-flex e-con e-child\" data-id=\"e3d15cd\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-547e366 elementor-widget elementor-widget-heading\" data-id=\"547e366\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Handhabung und Reinigung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4f36ae elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c4f36ae\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Fassen Sie die K\u00fcvetten immer mit sauberen Handschuhen an, um Fingerabdr\u00fccke auf den optischen Oberfl\u00e4chen zu vermeiden.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Reinigen Sie mit einem milden Reinigungsmittel (pH 7-8) und sp\u00fclen Sie es anschlie\u00dfend gr\u00fcndlich mit destilliertem Wasser ab.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">F\u00fcr organische R\u00fcckst\u00e4nde verwenden Sie L\u00f6sungsmittel von spektroskopischer Qualit\u00e4t (Aceton, Ethanol), gefolgt von einer Wassersp\u00fclung.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Vermeiden Sie scheuernde Materialien oder B\u00fcrsten, die optische Oberfl\u00e4chen zerkratzen k\u00f6nnten.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Trocknen Sie mit sauberer, komprimierter Luft oder Stickstoff, anstatt zu wischen.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7d3fbec e-con-full e-flex e-con e-child\" data-id=\"7d3fbec\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-00e113e e-con-full e-flex e-con e-child\" data-id=\"00e113e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2a8f06a elementor-widget elementor-widget-heading\" data-id=\"2a8f06a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Lagerung und Wartung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5a3d31 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a5a3d31\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Bewahren Sie es in der Original-Schutzh\u00fclle oder in einer staubfreien Umgebung auf.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Vermeiden Sie schnelle Temperaturschwankungen, die zu thermischem Stress f\u00fchren k\u00f6nnten.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pr\u00fcfen Sie regelm\u00e4\u00dfig auf Absplitterungen, Risse oder Oberfl\u00e4chenverschmutzung.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">F\u00fcr eine langfristige Lagerung m\u00fcssen die K\u00fcvetten gr\u00fcndlich gereinigt und trocken sein.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">F\u00fchren Sie ein Inventarverzeichnis, das auch die Nutzungshistorie und die Reinigungszyklen enth\u00e4lt.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-129592e e-con-full e-flex e-con e-child\" data-id=\"129592e\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-be04271 e-con-full e-flex e-con e-child\" data-id=\"be04271\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a35c2a1 elementor-widget elementor-widget-heading\" data-id=\"a35c2a1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Laden und Messen von Proben<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66aa22f elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"66aa22f\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">F\u00fcllen Sie bis zur empfohlenen Menge, um eine korrekte Ausrichtung des Lichtweges zu gew\u00e4hrleisten.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Vermeiden Sie Luftblasen, indem Sie die K\u00fcvette beim Bef\u00fcllen leicht kippen.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Reinigen Sie die optischen Fenster vor dem Einsetzen in das Ger\u00e4t mit einem Linsentuch.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Achten Sie auf die korrekte Ausrichtung mit dem Lichtweg senkrecht zum Strahl.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Bei gepaarten K\u00fcvetten ist auf eine einheitliche Ausrichtung von Referenz und Probe zu achten.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-beca90d e-con-full e-flex e-con e-child\" data-id=\"beca90d\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-637be98 e-con-full e-flex e-con e-child\" data-id=\"637be98\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-19d2ab8 elementor-widget elementor-widget-heading\" data-id=\"19d2ab8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Chemische Vertr\u00e4glichkeit<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4519a7 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c4519a7\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Vertr\u00e4glich mit den meisten S\u00e4uren, Basen und organischen L\u00f6sungsmitteln (au\u00dfer HF).<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Vermeiden Sie eine l\u00e4ngere Einwirkung von konzentrierten alkalischen L\u00f6sungen \u00fcber pH 12.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Bei \u00e4tzenden oder reaktiven Proben sofort nach Gebrauch absp\u00fclen.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Bei Proben, die Fluoridverbindungen enthalten, ist die Einwirkungszeit zu begrenzen und gr\u00fcndlich zu sp\u00fclen.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Bei ungew\u00f6hnlichen oder hochreaktiven Proben testen Sie die Kompatibilit\u00e4t zun\u00e4chst an einer Ersatzk\u00fcvette.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-77ef891 e-con-full e-flex e-con e-parent\" data-id=\"77ef891\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e3047ab e-con-full e-flex e-con e-child\" data-id=\"e3047ab\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9846296 elementor-widget__width-inherit elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-invisible elementor-widget elementor-widget-call-to-action\" data-id=\"9846296\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tBen\u00f6tigen Sie fachkundige Unterst\u00fctzung f\u00fcr Ihre UV-Grade Dual-Path Quarzk\u00fcvette?\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tDie Ingenieure von TOQUARTZ\u00ae helfen Ihnen gerne bei der Auswahl oder Entwicklung der perfekten UV-Grade Dual-Path Quarzk\u00fcvette f\u00fcr Ihre Anwendung.\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjczNyIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\tKontakt zu unserem Ingenieur\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d489546 e-flex e-con-boxed e-con e-parent\" data-id=\"d489546\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-69b5d01 e-con-full e-flex e-con e-child\" data-id=\"69b5d01\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dfa4ac4 elementor-widget elementor-widget-heading\" data-id=\"dfa4ac4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Warum eine Partnerschaft mit TOQUARTZ<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6ee975d e-con-full e-flex e-con e-child\" data-id=\"6ee975d\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ddb22ce e-con-full e-flex e-con e-child\" data-id=\"ddb22ce\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-45ce781 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"45ce781\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tVorteil der direkten Fabrik\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAls direkter Hersteller k\u00f6nnen wir die zahlreichen Zwischenstufen ausschalten.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4ccb3c8 e-con-full e-flex e-con e-child\" data-id=\"4ccb3c8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b90bf68 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"b90bf68\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-user-graduate\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tTechnische Kompetenz\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDas technische Team begleitet die Kunden von der Materialauswahl bis zur Designoptimierung und setzt die Spezifikationen in Ergebnisse um.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f587ce0 e-con-full e-flex e-con e-child\" data-id=\"f587ce0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1bb693d elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"1bb693d\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-edit\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tFlexible Fertigung\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tBearbeitung von Standard- und kundenspezifischen Auftr\u00e4gen mit Hilfe von Kleinserien und Prototyping, um dringende Fristen einzuhalten.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b5e7412 e-con-full e-flex e-con e-child\" data-id=\"b5e7412\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-608eea6 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"608eea6\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-shield-alt\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tQualit\u00e4t <br>Versicherung\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t3-Stufen-Validierung vor dem Versand:<br>1. Ma\u00dfhaltigkeit, <br>2. Materialreinheit , <br>3. Leistungsschwellen \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-51d5453 e-con-full e-flex e-con e-child\" data-id=\"51d5453\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-68ed5aa elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"68ed5aa\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-ship\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tGlobale Lieferkette\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tZuverl\u00e4ssige globale Logistik zu den industriellen Zentren (Priorit\u00e4t DE\/US\/JP\/KR) mit nachvollziehbaren Meilensteinen.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e6bacf7 e-flex e-con-boxed e-con e-parent\" data-id=\"e6bacf7\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-75cd0bf elementor-widget elementor-widget-heading\" data-id=\"75cd0bf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wiederverwertete Produkte<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-373f038 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"373f038\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Als spezialisierter Hersteller mit direkten Fertigungsm\u00f6glichkeiten bietet TOQUARTZ sowohl Standard- als auch kundenspezifische Quarzl\u00f6sungen mit technischer Unterst\u00fctzung w\u00e4hrend des gesamten Spezifikations- und Implementierungsprozesses. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-72b8dbf e-flex e-con-boxed e-con e-parent\" data-id=\"72b8dbf\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e77545b e-con-full e-flex e-con e-child\" data-id=\"e77545b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-69823be elementor-widget elementor-widget-heading\" data-id=\"69823be\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQ<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ea31dc elementor-widget elementor-widget-n-accordion\" data-id=\"8ea31dc\" data-element_type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Akkordeon. \u00d6ffnen Sie Links mit Enter oder Space, schlie\u00dfen Sie sie mit Escape und navigieren Sie mit den Pfeiltasten.\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1490\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-1490\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> F: Welche Standardpfadl\u00e4ngen sind f\u00fcr die UV-Grade Dual-Path-Quarzk\u00fcvetten erh\u00e4ltlich? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1490\" class=\"elementor-element elementor-element-fe22b54 e-con-full e-flex e-con e-child\" data-id=\"fe22b54\" data-element_type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1490\" class=\"elementor-element elementor-element-3515b0f e-flex e-con-boxed e-con e-child\" data-id=\"3515b0f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a9d99e elementor-widget elementor-widget-text-editor\" data-id=\"3a9d99e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>A: Die TOQUARTZ\u00ae-Standardpfadl\u00e4ngen umfassen 1mm, 2mm, 5mm, 10mm, 20mm, 50mm und 100mm. Die am h\u00e4ufigsten verwendete Pfadl\u00e4nge ist 10 mm, die mit den meisten Spektralphotometern kompatibel ist. Wir bieten auch kundenspezifische Pfadl\u00e4ngen zwischen 0,5 mm und 100 mm an, um spezifische Anwendungsanforderungen zu erf\u00fcllen. Alle Pfadl\u00e4ngen werden mit einer Toleranz von \u00b10,01 mm gefertigt, um die Messgenauigkeit zu gew\u00e4hrleisten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1491\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1491\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> F: Wie sollte ich UV-Doppelweg-Quarzk\u00fcvetten reinigen, um die optische Leistung zu erhalten? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1491\" class=\"elementor-element elementor-element-839bc12 e-con-full e-flex e-con e-child\" data-id=\"839bc12\" data-element_type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1491\" class=\"elementor-element elementor-element-dfc1971 e-flex e-con-boxed e-con e-child\" data-id=\"dfc1971\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-593df0e elementor-widget elementor-widget-text-editor\" data-id=\"593df0e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>A: F\u00fcr die Routinereinigung empfehlen wir die Verwendung einer milden Reinigungsl\u00f6sung (pH 7-8), gefolgt von einer gr\u00fcndlichen Sp\u00fclung mit destilliertem oder deionisiertem Wasser. Bei hartn\u00e4ckigeren R\u00fcckst\u00e4nden k\u00f6nnen spektroskopische L\u00f6sungsmittel wie Aceton oder Ethanol verwendet werden, die anschlie\u00dfend mit Wasser abgesp\u00fclt werden. Vermeiden Sie stets scheuernde Materialien oder B\u00fcrsten, die die optischen Oberfl\u00e4chen zerkratzen k\u00f6nnten. Trocknen Sie mit sauberer, komprimierter Luft oder Stickstoff, anstatt zu wischen. Detaillierte Reinigungsprotokolle f\u00fcr bestimmte Probentypen finden Sie in unserer vollst\u00e4ndigen Gebrauchsanweisung.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1492\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1492\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> F: Wie hoch ist die Temperaturbest\u00e4ndigkeit Ihrer UV-Grade Dual-Path Quarzk\u00fcvetten? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1492\" class=\"elementor-element elementor-element-fee5b6f e-con-full e-flex e-con e-child\" data-id=\"fee5b6f\" data-element_type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1492\" class=\"elementor-element elementor-element-99e397b e-flex e-con-boxed e-con e-child\" data-id=\"99e397b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c54852 elementor-widget elementor-widget-text-editor\" data-id=\"1c54852\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>A: TOQUARTZ\u00ae UV-Grade Dual-Path-Quarzk\u00fcvetten k\u00f6nnen Temperaturen von bis zu 1100\u00b0C standhalten und sind somit f\u00fcr Hochtemperaturanwendungen geeignet. Wir empfehlen jedoch, bei Standardausf\u00fchrungen 600\u00b0C nicht zu \u00fcberschreiten, um eine m\u00f6gliche Belastung von N\u00e4hten oder Verbindungen zu vermeiden. Bei schnellen Temperaturwechseln empfehlen wir, die Rate auf 10\u00b0C\/Minute zu begrenzen, um einen Temperaturschock zu vermeiden. F\u00fcr Anwendungen, die extreme Temperaturschwankungen oder Temperaturen von \u00fcber 600\u00b0C erfordern, wenden Sie sich bitte an unser Ingenieurteam f\u00fcr speziell entwickelte Hochtemperaturversionen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1493\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1493\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> F: Kann TOQUARTZ\u00ae UV-Grade Dual-Path Quarzk\u00fcvetten mit zertifizierter optischer Ebenheit anbieten? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1493\" class=\"elementor-element elementor-element-9ff89d5 e-con-full e-flex e-con e-child\" data-id=\"9ff89d5\" data-element_type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1493\" class=\"elementor-element elementor-element-559f6cb e-flex e-con-boxed e-con e-child\" data-id=\"559f6cb\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e650d42 elementor-widget elementor-widget-text-editor\" data-id=\"e650d42\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>A: Ja, wir bieten eine Zertifizierung der optischen Oberfl\u00e4chenebenheit bis zu \u2264\u03bb\/4 an, die mit Zygo-Interferometern f\u00fcr hochpr\u00e4zise Anwendungen \u00fcberpr\u00fcft wird.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1494\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1494\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> F: Werden Ihre UV-Doppelweg-Quarzk\u00fcvetten auf Doppelbrechung oder innere Spannungen getestet? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1494\" class=\"elementor-element elementor-element-90859c8 e-con-full e-flex e-con e-child\" data-id=\"90859c8\" data-element_type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1494\" class=\"elementor-element elementor-element-b93252b e-flex e-con-boxed e-con e-child\" data-id=\"b93252b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-67f3a38 elementor-widget elementor-widget-text-editor\" data-id=\"67f3a38\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>A: Ja, wir f\u00fchren Doppelbrechungstests mit polarisiertem Licht durch, um sicherzustellen, dass die innere Spannung unter 10 nm\/cm liegt, was f\u00fcr hochpr\u00e4zise optische Systeme entscheidend ist.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e50991d e-con-full e-flex e-con e-child\" data-id=\"e50991d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3e78480 elementor-widget elementor-widget-template\" data-id=\"3e78480\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"410\" class=\"elementor elementor-410\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-19500ba e-flex e-con-boxed e-con e-parent\" data-id=\"19500ba\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de5934c elementor-button-align-end elementor-widget elementor-widget-form\" data-id=\"de5934c\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" aria-label=\"Neue Form\" action=\"\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"410\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"de5934c\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"TOQUARTZ: Quartz Glass Solution\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_1400b18 elementor-col-33\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_1400b18\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tName\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_1400b18]\" id=\"form-field-field_1400b18\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"Ihren Namen eingeben\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-33 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tE-Mail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"*Add Your Email ID\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_47e7032 elementor-col-33\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_47e7032\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tName\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_47e7032]\" id=\"form-field-field_47e7032\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"Name des Unternehmens\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tNachricht\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-xs\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Geben Sie Ihre Nachricht ein...\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-upload elementor-field-group elementor-column elementor-field-group-field_91e5420 elementor-col-100\">\n\t\t\t\t\t\t\t<input type=\"file\" name=\"form_fields[field_91e5420][]\" id=\"form-field-field_91e5420\" class=\"elementor-field elementor-size-xs  elementor-upload-field\" multiple=\"multiple\" data-maxsize=\"50\" data-maxsize-message=\"This file exceeds the maximum allowed size.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text\">\n\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_5109d3b]\" id=\"form-field-field_5109d3b\" class=\"elementor-field elementor-size-xs\" style=\"display:none !important;\">\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt sofortiges Angebot<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"de\"\/><\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9db6355 elementor-widget elementor-widget-text-editor\" data-id=\"9db6355\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Wenden Sie sich f\u00fcr technische Beratung und Preisgestaltung an unser Ingenieurteam. Wir helfen Ihnen bei der Auswahl der optimalen Spezifikationen f\u00fcr Ihre Anwendungsanforderungen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Optimierte 6-seitige UV-Quarz-Durchflussk\u00fcvette f\u00fcr die Spektroskopie mit Mehrfachwinkel-Detektion - TOQUARTZ\u00ae<\/p>","protected":false},"author":2,"featured_media":8739,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[39,17,59,38,60,13],"tags":[],"class_list":["post-8734","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-optical-quartz-glass","category-products","category-quartz-cuvette","category-quartz-labware","category-quartz-uv-cuvette","category-types"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Spectral-Flat Custom UV-Grade Dual-Path Quartz Cuvette for UV-Vis Analysis\u4e28TOQUARTZ\u00ae<\/title>\n<meta name=\"description\" content=\"TOQUARTZ\u00ae Spectral-flat Custom UV-Grade Dual-Path Quartz Cuvette offers full-range UV-Vis transmission with no absorption peaks. Suitable for fluorescence and medical analysis.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/toquartz.com\/de\/custom-uv-grade-dual-path-quartz-cuvette\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spectral-Flat Custom UV-Grade Dual-Path Quartz Cuvette for UV-Vis Applications -TOQUARTZ\u00ae\u200b\" \/>\n<meta property=\"og:description\" content=\"TOQUARTZ\u00ae Spectral-flat Custom UV-Grade Dual-Path Quartz Cuvette offers full-range UV-Vis transmission with no absorption peaks. Suitable for fluorescence and medical analysis.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/toquartz.com\/de\/custom-uv-grade-dual-path-quartz-cuvette\/\" \/>\n<meta property=\"og:site_name\" content=\"TOQUARTZ: Quartz Glass Solution\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-05T08:10:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-30T09:11:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/toquartz.com\/wp-content\/uploads\/2025\/08\/High-purity-UV-Grade-Dual-Path-Quartz-Cuvette-for-spectroscopy-applications.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"ECHO\u00a0YANG\u200b\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"ECHO\u00a0YANG\u200b\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/toquartz.com\\\/custom-uv-grade-dual-path-quartz-cuvette\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toquartz.com\\\/custom-uv-grade-dual-path-quartz-cuvette\\\/\"},\"author\":{\"name\":\"ECHO\u00a0YANG\u200b\",\"@id\":\"https:\\\/\\\/toquartz.com\\\/#\\\/schema\\\/person\\\/64de60160e69ad73646f68c4a56a90d3\"},\"headline\":\"Spectral-Flat Custom UV-Grade Dual-Path Quartz Cuvette for UV-Vis Applications -TOQUARTZ\u00ae\u200b\",\"datePublished\":\"2025-08-05T08:10:32+00:00\",\"dateModified\":\"2025-09-30T09:11:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/toquartz.com\\\/custom-uv-grade-dual-path-quartz-cuvette\\\/\"},\"wordCount\":22,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/toquartz.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/toquartz.com\\\/custom-uv-grade-dual-path-quartz-cuvette\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/toquartz.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/High-purity-UV-Grade-Dual-Path-Quartz-Cuvette-for-spectroscopy-applications.webp\",\"articleSection\":[\"Optical Quartz Glass\",\"Products\",\"Quartz Cuvette\",\"Quartz Labware\",\"Quartz UV Cuvette\",\"Types\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/toquartz.com\\\/custom-uv-grade-dual-path-quartz-cuvette\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toquartz.com\\\/custom-uv-grade-dual-path-quartz-cuvette\\\/\",\"url\":\"https:\\\/\\\/toquartz.com\\\/custom-uv-grade-dual-path-quartz-cuvette\\\/\",\"name\":\"Spectral-Flat Custom UV-Grade Dual-Path Quartz Cuvette for UV-Vis Analysis\u4e28TOQUARTZ\u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toquartz.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/toquartz.com\\\/custom-uv-grade-dual-path-quartz-cuvette\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/toquartz.com\\\/custom-uv-grade-dual-path-quartz-cuvette\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/toquartz.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/High-purity-UV-Grade-Dual-Path-Quartz-Cuvette-for-spectroscopy-applications.webp\",\"datePublished\":\"2025-08-05T08:10:32+00:00\",\"dateModified\":\"2025-09-30T09:11:54+00:00\",\"description\":\"TOQUARTZ\u00ae Spectral-flat Custom UV-Grade Dual-Path Quartz Cuvette offers full-range UV-Vis transmission with no absorption peaks. Suitable for fluorescence and medical analysis.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toquartz.com\\\/custom-uv-grade-dual-path-quartz-cuvette\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/toquartz.com\\\/custom-uv-grade-dual-path-quartz-cuvette\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/toquartz.com\\\/custom-uv-grade-dual-path-quartz-cuvette\\\/#primaryimage\",\"url\":\"https:\\\/\\\/toquartz.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/High-purity-UV-Grade-Dual-Path-Quartz-Cuvette-for-spectroscopy-applications.webp\",\"contentUrl\":\"https:\\\/\\\/toquartz.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/High-purity-UV-Grade-Dual-Path-Quartz-Cuvette-for-spectroscopy-applications.webp\",\"width\":800,\"height\":800,\"caption\":\"High-purity UV-Grade Dual-Path Quartz Cuvette for spectroscopy applications\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toquartz.com\\\/custom-uv-grade-dual-path-quartz-cuvette\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toquartz.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Types\",\"item\":\"https:\\\/\\\/toquartz.com\\\/types\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Quartz Cuvette\",\"item\":\"https:\\\/\\\/toquartz.com\\\/types\\\/quartz-cuvette\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Quartz UV Cuvette\",\"item\":\"https:\\\/\\\/toquartz.com\\\/types\\\/quartz-cuvette\\\/quartz-uv-cuvette\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Spectral-Flat Custom UV-Grade Dual-Path Quartz Cuvette for UV-Vis Applications -TOQUARTZ\u00ae\u200b\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toquartz.com\\\/#website\",\"url\":\"https:\\\/\\\/toquartz.com\\\/\",\"name\":\"TOQUARTZ\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/toquartz.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/toquartz.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/toquartz.com\\\/#organization\",\"name\":\"TOQUARTZ\",\"url\":\"https:\\\/\\\/toquartz.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/toquartz.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/toquartz.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-2.png\",\"contentUrl\":\"https:\\\/\\\/toquartz.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-2.png\",\"width\":583,\"height\":151,\"caption\":\"TOQUARTZ\"},\"image\":{\"@id\":\"https:\\\/\\\/toquartz.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/toquartz.com\\\/#\\\/schema\\\/person\\\/64de60160e69ad73646f68c4a56a90d3\",\"name\":\"ECHO\u00a0YANG\u200b\",\"url\":\"https:\\\/\\\/toquartz.com\\\/de\\\/author\\\/webadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Spectral-Flat Custom UV-Grade Dual-Path Quarzk\u00fcvette f\u00fcr die UV-Vis Analyse\u4e28TOQUARTZ\u00ae","description":"Die TOQUARTZ\u00ae Spectral-flat Custom UV-Grade Dual-Path Quarzk\u00fcvette bietet eine UV-Vis-Transmission im gesamten Bereich ohne Absorptionsspitzen. Geeignet f\u00fcr Fluoreszenz und medizinische Analysen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/toquartz.com\/de\/custom-uv-grade-dual-path-quartz-cuvette\/","og_locale":"de_DE","og_type":"article","og_title":"Spectral-Flat Custom UV-Grade Dual-Path Quartz Cuvette for UV-Vis Applications -TOQUARTZ\u00ae\u200b","og_description":"TOQUARTZ\u00ae Spectral-flat Custom UV-Grade Dual-Path Quartz Cuvette offers full-range UV-Vis transmission with no absorption peaks. Suitable for fluorescence and medical analysis.","og_url":"https:\/\/toquartz.com\/de\/custom-uv-grade-dual-path-quartz-cuvette\/","og_site_name":"TOQUARTZ: Quartz Glass Solution","article_published_time":"2025-08-05T08:10:32+00:00","article_modified_time":"2025-09-30T09:11:54+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/toquartz.com\/wp-content\/uploads\/2025\/08\/High-purity-UV-Grade-Dual-Path-Quartz-Cuvette-for-spectroscopy-applications.webp","type":"image\/webp"}],"author":"ECHO\u00a0YANG\u200b","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"ECHO\u00a0YANG\u200b","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/toquartz.com\/custom-uv-grade-dual-path-quartz-cuvette\/#article","isPartOf":{"@id":"https:\/\/toquartz.com\/custom-uv-grade-dual-path-quartz-cuvette\/"},"author":{"name":"ECHO\u00a0YANG\u200b","@id":"https:\/\/toquartz.com\/#\/schema\/person\/64de60160e69ad73646f68c4a56a90d3"},"headline":"Spectral-Flat Custom UV-Grade Dual-Path Quartz Cuvette for UV-Vis Applications -TOQUARTZ\u00ae\u200b","datePublished":"2025-08-05T08:10:32+00:00","dateModified":"2025-09-30T09:11:54+00:00","mainEntityOfPage":{"@id":"https:\/\/toquartz.com\/custom-uv-grade-dual-path-quartz-cuvette\/"},"wordCount":22,"commentCount":0,"publisher":{"@id":"https:\/\/toquartz.com\/#organization"},"image":{"@id":"https:\/\/toquartz.com\/custom-uv-grade-dual-path-quartz-cuvette\/#primaryimage"},"thumbnailUrl":"https:\/\/toquartz.com\/wp-content\/uploads\/2025\/08\/High-purity-UV-Grade-Dual-Path-Quartz-Cuvette-for-spectroscopy-applications.webp","articleSection":["Optical Quartz Glass","Products","Quartz Cuvette","Quartz Labware","Quartz UV Cuvette","Types"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/toquartz.com\/custom-uv-grade-dual-path-quartz-cuvette\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/toquartz.com\/custom-uv-grade-dual-path-quartz-cuvette\/","url":"https:\/\/toquartz.com\/custom-uv-grade-dual-path-quartz-cuvette\/","name":"Spectral-Flat Custom UV-Grade Dual-Path Quarzk\u00fcvette f\u00fcr die UV-Vis Analyse\u4e28TOQUARTZ\u00ae","isPartOf":{"@id":"https:\/\/toquartz.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/toquartz.com\/custom-uv-grade-dual-path-quartz-cuvette\/#primaryimage"},"image":{"@id":"https:\/\/toquartz.com\/custom-uv-grade-dual-path-quartz-cuvette\/#primaryimage"},"thumbnailUrl":"https:\/\/toquartz.com\/wp-content\/uploads\/2025\/08\/High-purity-UV-Grade-Dual-Path-Quartz-Cuvette-for-spectroscopy-applications.webp","datePublished":"2025-08-05T08:10:32+00:00","dateModified":"2025-09-30T09:11:54+00:00","description":"Die TOQUARTZ\u00ae Spectral-flat Custom UV-Grade Dual-Path Quarzk\u00fcvette bietet eine UV-Vis-Transmission im gesamten Bereich ohne Absorptionsspitzen. Geeignet f\u00fcr Fluoreszenz und medizinische Analysen.","breadcrumb":{"@id":"https:\/\/toquartz.com\/custom-uv-grade-dual-path-quartz-cuvette\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/toquartz.com\/custom-uv-grade-dual-path-quartz-cuvette\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/toquartz.com\/custom-uv-grade-dual-path-quartz-cuvette\/#primaryimage","url":"https:\/\/toquartz.com\/wp-content\/uploads\/2025\/08\/High-purity-UV-Grade-Dual-Path-Quartz-Cuvette-for-spectroscopy-applications.webp","contentUrl":"https:\/\/toquartz.com\/wp-content\/uploads\/2025\/08\/High-purity-UV-Grade-Dual-Path-Quartz-Cuvette-for-spectroscopy-applications.webp","width":800,"height":800,"caption":"High-purity UV-Grade Dual-Path Quartz Cuvette for spectroscopy applications"},{"@type":"BreadcrumbList","@id":"https:\/\/toquartz.com\/custom-uv-grade-dual-path-quartz-cuvette\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/toquartz.com\/"},{"@type":"ListItem","position":2,"name":"Types","item":"https:\/\/toquartz.com\/types\/"},{"@type":"ListItem","position":3,"name":"Quartz Cuvette","item":"https:\/\/toquartz.com\/types\/quartz-cuvette\/"},{"@type":"ListItem","position":4,"name":"Quartz UV Cuvette","item":"https:\/\/toquartz.com\/types\/quartz-cuvette\/quartz-uv-cuvette\/"},{"@type":"ListItem","position":5,"name":"Spectral-Flat Custom UV-Grade Dual-Path Quartz Cuvette for UV-Vis Applications -TOQUARTZ\u00ae\u200b"}]},{"@type":"WebSite","@id":"https:\/\/toquartz.com\/#website","url":"https:\/\/toquartz.com\/","name":"TOQUARTZ","description":"","publisher":{"@id":"https:\/\/toquartz.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/toquartz.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/toquartz.com\/#organization","name":"TOQUARTZ","url":"https:\/\/toquartz.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/toquartz.com\/#\/schema\/logo\/image\/","url":"https:\/\/toquartz.com\/wp-content\/uploads\/2025\/02\/logo-2.png","contentUrl":"https:\/\/toquartz.com\/wp-content\/uploads\/2025\/02\/logo-2.png","width":583,"height":151,"caption":"TOQUARTZ"},"image":{"@id":"https:\/\/toquartz.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/toquartz.com\/#\/schema\/person\/64de60160e69ad73646f68c4a56a90d3","name":"ECHO YANG","url":"https:\/\/toquartz.com\/de\/author\/webadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/toquartz.com\/de\/wp-json\/wp\/v2\/posts\/8734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toquartz.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toquartz.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toquartz.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/toquartz.com\/de\/wp-json\/wp\/v2\/comments?post=8734"}],"version-history":[{"count":5,"href":"https:\/\/toquartz.com\/de\/wp-json\/wp\/v2\/posts\/8734\/revisions"}],"predecessor-version":[{"id":8749,"href":"https:\/\/toquartz.com\/de\/wp-json\/wp\/v2\/posts\/8734\/revisions\/8749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/toquartz.com\/de\/wp-json\/wp\/v2\/media\/8739"}],"wp:attachment":[{"href":"https:\/\/toquartz.com\/de\/wp-json\/wp\/v2\/media?parent=8734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toquartz.com\/de\/wp-json\/wp\/v2\/categories?post=8734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toquartz.com\/de\/wp-json\/wp\/v2\/tags?post=8734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}